{"id":11780,"date":"2025-09-10T18:15:24","date_gmt":"2025-09-10T16:15:24","guid":{"rendered":"https:\/\/cdgolf33.com\/?page_id=11780"},"modified":"2025-09-16T12:32:43","modified_gmt":"2025-09-16T10:32:43","slug":"les-resultats-de-la-finale-interclubs-par-equipes","status":"publish","type":"page","link":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/","title":{"rendered":"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes"},"content":{"rendered":"\n<h3><strong>Les r\u00e9sultats de la finale interclubs par \u00e9quipes d\u00e9roul\u00e9e sur 3 parties au Golf de Gujan-Mestras le 7 septembre 2025.<\/strong><\/h3>\n<p>-Individuel par \u00e9quipes<\/p>\n<p>-Scramble par \u00e9quipes<\/p>\n<p>-Foursome par \u00e9quipes<\/p>\n<p><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/cdgolf33.com\/wp-content\/uploads\/2025\/09\/Resultats_finale_interclubs_2025.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 R\u00e9sultats_finale_interclubs_2025.\"><\/object><a id=\"wp-block-file--media-0039b99f-a2fd-49c5-b729-4bf239b94ebc\" href=\"https:\/\/cdgolf33.com\/wp-content\/uploads\/2025\/09\/Resultats_finale_interclubs_2025.pdf\">R\u00e9sultats_finale_interclubs_2025<\/a><a href=\"https:\/\/cdgolf33.com\/wp-content\/uploads\/2025\/09\/Resultats_finale_interclubs_2025.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0039b99f-a2fd-49c5-b729-4bf239b94ebc\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p>Mise \u00e0 jour : 16\/09\/23025.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><input type=\"button\" value=\"Retour\" class=\"alg_back_button_input button\" style=\"background-color:#61B6CE\" onclick=\"window.history.back()\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9sultats de la finale interclubs par \u00e9quipes d\u00e9roul\u00e9e sur 3 parties au Golf de Gujan-Mestras le 7 septembre 2025. -Individuel par \u00e9quipes -Scramble par \u00e9quipes -Foursome par \u00e9quipes Mise \u00e0 jour : 16\/09\/23025.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11780","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9sultats de la finale interclubs par \u00e9quipes d\u00e9roul\u00e9e sur 3 parties au Golf de Gujan-Mestras le 7 septembre 2025. -Individuel par \u00e9quipes -Scramble par \u00e9quipes -Foursome par \u00e9quipes Mise \u00e0 jour : 16\/09\/23025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/\" \/>\n<meta property=\"og:site_name\" content=\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T10:32:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/les-resultats-de-la-finale-interclubs-par-equipes\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/les-resultats-de-la-finale-interclubs-par-equipes\\\/\",\"name\":\"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\"},\"datePublished\":\"2025-09-10T16:15:24+00:00\",\"dateModified\":\"2025-09-16T10:32:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/les-resultats-de-la-finale-interclubs-par-equipes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/les-resultats-de-la-finale-interclubs-par-equipes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/les-resultats-de-la-finale-interclubs-par-equipes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cdgolf33.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"name\":\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"description\":\"Le Comit\u00e9 de Gironde de Golf vous souhaite la bienvenue sur son site !\",\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cdgolf33.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\",\"name\":\"Comit\u00e9 de Golf de Gironde\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"contentUrl\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"width\":220,\"height\":233,\"caption\":\"Comit\u00e9 de Golf de Gironde\"},\"image\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/comitegolf33\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/","og_locale":"fr_FR","og_type":"article","og_title":"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde","og_description":"Les r\u00e9sultats de la finale interclubs par \u00e9quipes d\u00e9roul\u00e9e sur 3 parties au Golf de Gujan-Mestras le 7 septembre 2025. -Individuel par \u00e9quipes -Scramble par \u00e9quipes -Foursome par \u00e9quipes Mise \u00e0 jour : 16\/09\/23025.","og_url":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/","og_site_name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","article_modified_time":"2025-09-16T10:32:43+00:00","twitter_card":"summary_large_image","twitter_site":"@comitegolf33","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/","url":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/","name":"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes - Comit\u00e9 D\u00e9partemental de Golf de Gironde","isPartOf":{"@id":"https:\/\/cdgolf33.com\/#website"},"datePublished":"2025-09-10T16:15:24+00:00","dateModified":"2025-09-16T10:32:43+00:00","breadcrumb":{"@id":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdgolf33.com\/index.php\/les-resultats-de-la-finale-interclubs-par-equipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cdgolf33.com\/"},{"@type":"ListItem","position":2,"name":"Pitch &amp; Putt 2025 : les r\u00e9sultats de la finale interclubs par \u00e9quipes"}]},{"@type":"WebSite","@id":"https:\/\/cdgolf33.com\/#website","url":"https:\/\/cdgolf33.com\/","name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","description":"Le Comit\u00e9 de Gironde de Golf vous souhaite la bienvenue sur son site !","publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdgolf33.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdgolf33.com\/#organization","name":"Comit\u00e9 de Golf de Gironde","url":"https:\/\/cdgolf33.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/","url":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","contentUrl":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","width":220,"height":233,"caption":"Comit\u00e9 de Golf de Gironde"},"image":{"@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/comitegolf33"]}]}},"_links":{"self":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/11780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/comments?post=11780"}],"version-history":[{"count":10,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/11780\/revisions"}],"predecessor-version":[{"id":11887,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/11780\/revisions\/11887"}],"wp:attachment":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/media?parent=11780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}