{"id":13222,"date":"2026-03-09T11:10:49","date_gmt":"2026-03-09T10:10:49","guid":{"rendered":"https:\/\/cdgolf33.com\/?page_id=13222"},"modified":"2026-03-30T13:58:54","modified_gmt":"2026-03-30T11:58:54","slug":"pitch-putt-2026-liste-des-inscrits-au-tour-n3","status":"publish","type":"page","link":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/","title":{"rendered":"Pitch &#038; Putt 2026 : Liste des inscrits au Tour N\u00b03"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13222\" class=\"elementor elementor-13222\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecd6c8b e-flex e-con-boxed e-con e-parent\" data-id=\"ecd6c8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab2b4d elementor-widget elementor-widget-text-editor\" data-id=\"4ab2b4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Liste des inscrits au Tour N\u00b03.<\/strong><\/p><p>Mise \u00e0 jour : 30\/03\/2026-14:00.<\/p><p><b style=\"font-size: inherit; font-family: var( --e-global-typography-text-font-family ), Sans-serif; text-align: var(--text-align); color: #000000;\">Les inscriptions sont limit\u00e9es \u00e0 108 joueurs\/joueuses.<\/b><\/p><p><strong>Les joueurs et joueuses sont list\u00e9(e)s par date et heure croissantes d&rsquo;inscription.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69243b4 e-flex e-con-boxed e-con e-parent\" data-id=\"69243b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50ff240 elementor-widget elementor-widget-counter\" data-id=\"50ff240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Nombre d'inscrits au Tour 3 2026<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"108\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f49ce41 elementor-widget elementor-widget-counter\" data-id=\"f49ce41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Nombre de droits d'engagement saison 2026<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"162\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e23f680 e-con-full e-flex e-con e-parent\" data-id=\"e23f680\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5f72a elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"6f5f72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe width=\"402\" height=\"346\" frameborder=\"0\" scrolling=\"no\" src=\"https:\/\/1drv.ms\/x\/c\/eb7f4b2553ac692d\/IQTbj0QodOn1SKTSIU5VWyr3Af9WsNzBCkw7-dugZYIcbZI?em=2&wdAllowInteractivity=False&wdHideGridlines=True&wdHideHeaders=True&wdDownloadButton=True&wdInConfigurator=True&wdInConfigurator=True\"><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b88a79 e-flex e-con-boxed e-con e-parent\" data-id=\"1b88a79\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87bbdfe elementor-widget elementor-widget-shortcode\" data-id=\"87bbdfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><input type=\"button\" value=\"Retour\" class=\"alg_back_button_input button\" style=\"background-color:#61B6CE\" onclick=\"window.history.back()\" \/><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Liste des inscrits au Tour N\u00b03. Mise \u00e0 jour : 30\/03\/2026-14:00. Les inscriptions sont limit\u00e9es \u00e0 108 joueurs\/joueuses. Les joueurs et joueuses sont list\u00e9(e)s par date et heure croissantes d&rsquo;inscription. Nombre d&rsquo;inscrits au Tour 3 2026 0 Nombre de droits d&rsquo;engagement saison 2026 0<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13222","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pitch &amp; Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pitch &amp; Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"og:description\" content=\"Liste des inscrits au Tour N\u00b03. Mise \u00e0 jour : 30\/03\/2026-14:00. Les inscriptions sont limit\u00e9es \u00e0 108 joueurs\/joueuses. Les joueurs et joueuses sont list\u00e9(e)s par date et heure croissantes d&rsquo;inscription. Nombre d&rsquo;inscrits au Tour 3 2026 0 Nombre de droits d&rsquo;engagement saison 2026 0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/\" \/>\n<meta property=\"og:site_name\" content=\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T11:58:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\\\/\",\"name\":\"Pitch & Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\"},\"datePublished\":\"2026-03-09T10:10:49+00:00\",\"dateModified\":\"2026-03-30T11:58:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cdgolf33.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pitch &#038; Putt 2026 : Liste des inscrits au Tour N\u00b03\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"name\":\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"description\":\"Le Comit\u00e9 de Golf de la Gironde vous souhaite la bienvenue sur son site !\",\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cdgolf33.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\",\"name\":\"Comit\u00e9 de Golf de Gironde\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"contentUrl\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"width\":220,\"height\":233,\"caption\":\"Comit\u00e9 de Golf de Gironde\"},\"image\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/comitegolf33\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pitch & Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/","og_locale":"fr_FR","og_type":"article","og_title":"Pitch & Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","og_description":"Liste des inscrits au Tour N\u00b03. Mise \u00e0 jour : 30\/03\/2026-14:00. Les inscriptions sont limit\u00e9es \u00e0 108 joueurs\/joueuses. Les joueurs et joueuses sont list\u00e9(e)s par date et heure croissantes d&rsquo;inscription. Nombre d&rsquo;inscrits au Tour 3 2026 0 Nombre de droits d&rsquo;engagement saison 2026 0","og_url":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/","og_site_name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","article_modified_time":"2026-03-30T11:58:54+00:00","twitter_card":"summary_large_image","twitter_site":"@comitegolf33","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/","url":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/","name":"Pitch & Putt 2026 : Liste des inscrits au Tour N\u00b03 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","isPartOf":{"@id":"https:\/\/cdgolf33.com\/#website"},"datePublished":"2026-03-09T10:10:49+00:00","dateModified":"2026-03-30T11:58:54+00:00","breadcrumb":{"@id":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdgolf33.com\/index.php\/pitch-putt-2026-liste-des-inscrits-au-tour-n3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cdgolf33.com\/"},{"@type":"ListItem","position":2,"name":"Pitch &#038; Putt 2026 : Liste des inscrits au Tour N\u00b03"}]},{"@type":"WebSite","@id":"https:\/\/cdgolf33.com\/#website","url":"https:\/\/cdgolf33.com\/","name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","description":"Le Comit\u00e9 de Golf de la Gironde vous souhaite la bienvenue sur son site !","publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdgolf33.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdgolf33.com\/#organization","name":"Comit\u00e9 de Golf de Gironde","url":"https:\/\/cdgolf33.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/","url":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","contentUrl":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","width":220,"height":233,"caption":"Comit\u00e9 de Golf de Gironde"},"image":{"@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/comitegolf33"]}]}},"_links":{"self":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/13222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/comments?post=13222"}],"version-history":[{"count":29,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/13222\/revisions"}],"predecessor-version":[{"id":13575,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/pages\/13222\/revisions\/13575"}],"wp:attachment":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/media?parent=13222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}