{"id":10671,"date":"2025-05-08T19:33:09","date_gmt":"2025-05-08T17:33:09","guid":{"rendered":"https:\/\/cdgolf33.com\/?p=10671"},"modified":"2025-05-09T15:36:14","modified_gmt":"2025-05-09T13:36:14","slug":"10671","status":"publish","type":"post","link":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/","title":{"rendered":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25"},"content":{"rendered":"<div dir=\"ltr\" data-olk-copy-source=\"MessageBody\">Vous trouverez ci-dessous la liste des d\u00e9parts pour samedi 10 mai prochain au<span>\u00a0<\/span><b>Golf de Cameyrac<\/b>\u00a0\u00e0 partir de 9h.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><u>Pour le bon d\u00e9roulement de cette journ\u00e9e, merci de bien respecter les consignes du r\u00e8glement :<\/u><\/div>\n<p class=\"x_MsoNormal\" dir=\"ltr\"><span>Les r\u00e8glements g\u00e9n\u00e9raux des \u00e9preuves de jeunes s\u2019appliquent, \u00e0 savoir\u00a0:<\/span><\/p>\n<ul>\n<li><span>\u00c9preuves \u00ab\u00a0non-fumeur\u00a0\u00bb.<\/span><\/li>\n<li><span>Les joueurs doivent avoir une tenue correcte (pas de blue-jean) et un comportement exemplaire (cf. R\u00e8glement G\u00e9n\u00e9ral sur le Vade-mecum 2025).<\/span><\/li>\n<li><span>Les cadets ne sont pas autoris\u00e9s m\u00eame pour les joueurs entre eux.<\/span><\/li>\n<li><span>L\u2019utilisation des chariots \u00e9lectriques n\u2019est pas autoris\u00e9e.<\/span><\/li>\n<li>\n<div><span>Seuls les professionnels sont autoris\u00e9s \u00e0 suivre \u00e0 distance (minimum de 50 m) les parties et aucun conseil n\u2019est autoris\u00e9<\/span><\/div>\n<\/li>\n<li><span style=\"color: #ff0000;\"><b>En cas de triche, de comportement inappropri\u00e9 sur le parcours et contraire \u00e0 l\u2019esprit sportif, le comit\u00e9 d\u00e9partemental infligera une suspension de 3 mois au joueur.<\/b><\/span><\/li>\n<li><span style=\"color: #ff0000;\"><b>Aucun parent ne sera admis sur le parcours sauf s\u2019il est d\u00e9sign\u00e9 marqueur d\u2019une partie par le Comit\u00e9 d\u00e9partemental.<\/b><\/span><\/li>\n<li><span style=\"color: #ff0000;\"><b>Un contr\u00f4le trou par trou sera fait par l\u2019adulte marqueur. Celui-ci se verra remettre une fiche de la FFGOLF \u00ab\u00a0Suiveur de partie en comp\u00e9tition\u00a0\u00bb<\/b><\/span><\/li>\n<li><span style=\"color: #ff0000;\"><b>Aucun parent ne pourra suivre la partie de son enfant.<\/b><\/span><\/li>\n<li><span>L\u2019utilisation des appareils de mesure de distance n\u2019est pas autoris\u00e9e lors des tours de comp\u00e9tition (article 1.2.8 du vademecum 2025). Son utilisation est autoris\u00e9e lors de la partie de reconnaissance.<\/span><\/li>\n<li>\n<div><span>Toute infraction aux r\u00e8gles ci-dessus entra\u00eene, apr\u00e8s un avertissement, la disqualification du joueur.<\/span><span><br \/>\n<\/span><\/div>\n<\/li>\n<\/ul>\n<blockquote>\n<div dir=\"ltr\">De plus, veuillez noter que les enfants ayant \u00e9t\u00e9 inscrits mais n\u2019ayant pas l\u2019index requis n\u2019ont pas de d\u00e9parts. Merci de bien vouloir faire bien attention pour le dernier tour qui aura lieu pendant les vacances de la Toussaint.<\/div>\n<\/blockquote>\n<div dir=\"ltr\" aria-hidden=\"true\"><\/div>\n<div dir=\"ltr\"><em>Si vous souhaitez d\u00e9jeuner au restaurant du golf, vous pouvez r\u00e9server au 05.57.04.27.30.<\/em><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/cdgolf33.com\/wp-content\/uploads\/2025\/05\/Departs-CHPT-DEP-U12-Cameyrac.pdf\" target=\"_blank\" rel=\"noopener\">&gt;&gt;&gt; De\u0301parts CHPT DEP U12 &#8211; Cameyrac<\/a><\/div>\n<div dir=\"ltr\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous la liste des d\u00e9parts pour samedi 10 mai prochain au\u00a0Golf de Cameyrac\u00a0\u00e0 partir de 9h. Pour le bon d\u00e9roulement de cette journ\u00e9e, merci de bien respecter les consignes du r\u00e8glement : Les r\u00e8glements g\u00e9n\u00e9raux des \u00e9preuves de jeunes s\u2019appliquent, \u00e0 savoir\u00a0: \u00c9preuves \u00ab\u00a0non-fumeur\u00a0\u00bb. Les joueurs doivent avoir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-10671","post","type-post","status-publish","format-standard","hentry","category-jeunes-chpt-gde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"og:description\" content=\"Vous trouverez ci-dessous la liste des d\u00e9parts pour samedi 10 mai prochain au\u00a0Golf de Cameyrac\u00a0\u00e0 partir de 9h. Pour le bon d\u00e9roulement de cette journ\u00e9e, merci de bien respecter les consignes du r\u00e8glement : Les r\u00e8glements g\u00e9n\u00e9raux des \u00e9preuves de jeunes s\u2019appliquent, \u00e0 savoir\u00a0: \u00c9preuves \u00ab\u00a0non-fumeur\u00a0\u00bb. Les joueurs doivent avoir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/\" \/>\n<meta property=\"og:site_name\" content=\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T17:33:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T13:36:14+00:00\" \/>\n<meta name=\"author\" content=\"le Comit\u00e9 de Golf de Gironde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:site\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"le Comit\u00e9 de Golf de Gironde\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/\"},\"author\":{\"name\":\"le Comit\u00e9 de Golf de Gironde\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/person\\\/0fe3a29db97d77dc619597e8963ba0f5\"},\"headline\":\"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\\\/05\\\/25\",\"datePublished\":\"2025-05-08T17:33:09+00:00\",\"dateModified\":\"2025-05-09T13:36:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"articleSection\":[\"Jeunes ~ Championnat D\u00e9partemental de Gironde\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/\",\"name\":\"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\\\/05\\\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\"},\"datePublished\":\"2025-05-08T17:33:09+00:00\",\"dateModified\":\"2025-05-09T13:36:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2025\\\/05\\\/08\\\/10671\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cdgolf33.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\\\/05\\\/25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"name\":\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"description\":\"Le Comit\u00e9 de Golf de la Gironde vous souhaite la bienvenue sur son site !\",\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cdgolf33.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\",\"name\":\"Comit\u00e9 de Golf de Gironde\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"contentUrl\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"width\":220,\"height\":233,\"caption\":\"Comit\u00e9 de Golf de Gironde\"},\"image\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/comitegolf33\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/person\\\/0fe3a29db97d77dc619597e8963ba0f5\",\"name\":\"le Comit\u00e9 de Golf de Gironde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"caption\":\"le Comit\u00e9 de Golf de Gironde\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/","og_locale":"fr_FR","og_type":"article","og_title":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","og_description":"Vous trouverez ci-dessous la liste des d\u00e9parts pour samedi 10 mai prochain au\u00a0Golf de Cameyrac\u00a0\u00e0 partir de 9h. Pour le bon d\u00e9roulement de cette journ\u00e9e, merci de bien respecter les consignes du r\u00e8glement : Les r\u00e8glements g\u00e9n\u00e9raux des \u00e9preuves de jeunes s\u2019appliquent, \u00e0 savoir\u00a0: \u00c9preuves \u00ab\u00a0non-fumeur\u00a0\u00bb. Les joueurs doivent avoir [&hellip;]","og_url":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/","og_site_name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","article_published_time":"2025-05-08T17:33:09+00:00","article_modified_time":"2025-05-09T13:36:14+00:00","author":"le Comit\u00e9 de Golf de Gironde","twitter_card":"summary_large_image","twitter_creator":"@comitegolf33","twitter_site":"@comitegolf33","twitter_misc":{"\u00c9crit par":"le Comit\u00e9 de Golf de Gironde","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/#article","isPartOf":{"@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/"},"author":{"name":"le Comit\u00e9 de Golf de Gironde","@id":"https:\/\/cdgolf33.com\/#\/schema\/person\/0fe3a29db97d77dc619597e8963ba0f5"},"headline":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25","datePublished":"2025-05-08T17:33:09+00:00","dateModified":"2025-05-09T13:36:14+00:00","mainEntityOfPage":{"@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/"},"wordCount":326,"publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"articleSection":["Jeunes ~ Championnat D\u00e9partemental de Gironde"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/","url":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/","name":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25 - Comit\u00e9 D\u00e9partemental de Golf de Gironde","isPartOf":{"@id":"https:\/\/cdgolf33.com\/#website"},"datePublished":"2025-05-08T17:33:09+00:00","dateModified":"2025-05-09T13:36:14+00:00","breadcrumb":{"@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdgolf33.com\/index.php\/2025\/05\/08\/10671\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cdgolf33.com\/"},{"@type":"ListItem","position":2,"name":"CHAMPIONNAT DEPARTEMENTAL U12 \u2013 D\u00c9PARTS DU 10\/05\/25"}]},{"@type":"WebSite","@id":"https:\/\/cdgolf33.com\/#website","url":"https:\/\/cdgolf33.com\/","name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","description":"Le Comit\u00e9 de Golf de la Gironde vous souhaite la bienvenue sur son site !","publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdgolf33.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdgolf33.com\/#organization","name":"Comit\u00e9 de Golf de Gironde","url":"https:\/\/cdgolf33.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/","url":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","contentUrl":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","width":220,"height":233,"caption":"Comit\u00e9 de Golf de Gironde"},"image":{"@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/comitegolf33"]},{"@type":"Person","@id":"https:\/\/cdgolf33.com\/#\/schema\/person\/0fe3a29db97d77dc619597e8963ba0f5","name":"le Comit\u00e9 de Golf de Gironde","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","caption":"le Comit\u00e9 de Golf de Gironde"}}]}},"_links":{"self":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts\/10671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/comments?post=10671"}],"version-history":[{"count":2,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts\/10671\/revisions"}],"predecessor-version":[{"id":10674,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts\/10671\/revisions\/10674"}],"wp:attachment":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/media?parent=10671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/categories?post=10671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/tags?post=10671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}