{"id":3210,"date":"2018-01-29T21:07:10","date_gmt":"2018-01-29T20:07:10","guid":{"rendered":"http:\/\/www.cdgolf33.com\/?p=3210"},"modified":"2018-01-29T21:07:10","modified_gmt":"2018-01-29T20:07:10","slug":"interclubs-dhiver-adultes","status":"publish","type":"post","link":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/","title":{"rendered":"INTERCLUBS D&rsquo;HIVER ADULTES"},"content":{"rendered":"<p>\t\t\t\t<u>MESSIEURS\u00a0:<\/u> Tous les matchs pr\u00e9vus hier chez les messieurs ont pu avoir lieu. La poule 2 est ainsi achev\u00e9e. Pour la poule 1, 2 matches n\u2019ont pas \u00e9t\u00e9 disput\u00e9s\u00a0: GB\/PES du 5 novembre (repouss\u00e9 par deux fois) et MED\/PES du 19 novembre (repouss\u00e9 puis arr\u00eat\u00e9 pour cause de greens inond\u00e9s). Nous avons d\u00e9cid\u00e9 de d\u00e9clarer match nul pour ces deux rencontres.<br \/>\nEn cons\u00e9quence les <u>finales du 4 f\u00e9vrier pourront avoir lieu<\/u> (cf. tableau). Les clubs recevant sont responsables de l\u2019organisation. Si un match doit \u00eatre repouss\u00e9, la date de remplacement devra nous \u00eatre communiqu\u00e9e. Une finale qui n\u2019aura pas \u00e9t\u00e9 disput\u00e9e le 4 mars sera r\u00e9put\u00e9e perdue par le club recevant.<\/p>\n<p><u>DAMES\u00a0:<\/u> pas d\u2019\u00e9volution. Les capitaines des dames sont pri\u00e9es de nous indiquer quand elles pr\u00e9voient de jouer ou si elles abandonnent.<\/p>\n<p>&nbsp;<\/p>\n<p>R\u00e9sultats connus \u00e0 ce jour:\u00a0<a href=\"http:\/\/www.cdgolf33.com\/wp-content\/uploads\/2018\/01\/2017-Classt-interclubs-hiver.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Classement 2017<\/a>\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MESSIEURS\u00a0: Tous les matchs pr\u00e9vus hier chez les messieurs ont pu avoir lieu. La poule 2 est ainsi achev\u00e9e. Pour la poule 1, 2 matches n\u2019ont pas \u00e9t\u00e9 disput\u00e9s\u00a0: GB\/PES du 5 novembre (repouss\u00e9 par deux fois) et MED\/PES du 19 novembre (repouss\u00e9 puis arr\u00eat\u00e9 pour cause de greens inond\u00e9s). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3210","post","type-post","status-publish","format-standard","hentry","category-ich-adultes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INTERCLUBS D&#039;HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INTERCLUBS D&#039;HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"og:description\" content=\"MESSIEURS\u00a0: Tous les matchs pr\u00e9vus hier chez les messieurs ont pu avoir lieu. La poule 2 est ainsi achev\u00e9e. Pour la poule 1, 2 matches n\u2019ont pas \u00e9t\u00e9 disput\u00e9s\u00a0: GB\/PES du 5 novembre (repouss\u00e9 par deux fois) et MED\/PES du 19 novembre (repouss\u00e9 puis arr\u00eat\u00e9 pour cause de greens inond\u00e9s). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/\" \/>\n<meta property=\"og:site_name\" content=\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-29T20:07:10+00:00\" \/>\n<meta name=\"author\" content=\"le Comit\u00e9 de Golf de Gironde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:site\" content=\"@comitegolf33\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"le Comit\u00e9 de Golf de Gironde\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/\"},\"author\":{\"name\":\"le Comit\u00e9 de Golf de Gironde\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/person\\\/0fe3a29db97d77dc619597e8963ba0f5\"},\"headline\":\"INTERCLUBS D&rsquo;HIVER ADULTES\",\"datePublished\":\"2018-01-29T20:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"articleSection\":[\"ICH ~ Interclubs d'Hiver Adultes\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/\",\"name\":\"INTERCLUBS D'HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\"},\"datePublished\":\"2018-01-29T20:07:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/index.php\\\/2018\\\/01\\\/29\\\/interclubs-dhiver-adultes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cdgolf33.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INTERCLUBS D&rsquo;HIVER ADULTES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#website\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"name\":\"Comit\u00e9 D\u00e9partemental de Golf de Gironde\",\"description\":\"Le Comit\u00e9 de Gironde de Golf vous souhaite la bienvenue sur son site !\",\"publisher\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cdgolf33.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#organization\",\"name\":\"Comit\u00e9 de Golf de Gironde\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"contentUrl\":\"https:\\\/\\\/cdgolf33.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/LOGOCD33.jpg\",\"width\":220,\"height\":233,\"caption\":\"Comit\u00e9 de Golf de Gironde\"},\"image\":{\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/comitegolf33\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cdgolf33.com\\\/#\\\/schema\\\/person\\\/0fe3a29db97d77dc619597e8963ba0f5\",\"name\":\"le Comit\u00e9 de Golf de Gironde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g\",\"caption\":\"le Comit\u00e9 de Golf de Gironde\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INTERCLUBS D'HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/","og_locale":"fr_FR","og_type":"article","og_title":"INTERCLUBS D'HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde","og_description":"MESSIEURS\u00a0: Tous les matchs pr\u00e9vus hier chez les messieurs ont pu avoir lieu. La poule 2 est ainsi achev\u00e9e. Pour la poule 1, 2 matches n\u2019ont pas \u00e9t\u00e9 disput\u00e9s\u00a0: GB\/PES du 5 novembre (repouss\u00e9 par deux fois) et MED\/PES du 19 novembre (repouss\u00e9 puis arr\u00eat\u00e9 pour cause de greens inond\u00e9s). [&hellip;]","og_url":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/","og_site_name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","article_published_time":"2018-01-29T20:07:10+00:00","author":"le Comit\u00e9 de Golf de Gironde","twitter_card":"summary_large_image","twitter_creator":"@comitegolf33","twitter_site":"@comitegolf33","twitter_misc":{"\u00c9crit par":"le Comit\u00e9 de Golf de Gironde","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/#article","isPartOf":{"@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/"},"author":{"name":"le Comit\u00e9 de Golf de Gironde","@id":"https:\/\/cdgolf33.com\/#\/schema\/person\/0fe3a29db97d77dc619597e8963ba0f5"},"headline":"INTERCLUBS D&rsquo;HIVER ADULTES","datePublished":"2018-01-29T20:07:10+00:00","mainEntityOfPage":{"@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/"},"wordCount":157,"publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"articleSection":["ICH ~ Interclubs d'Hiver Adultes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/","url":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/","name":"INTERCLUBS D'HIVER ADULTES - Comit\u00e9 D\u00e9partemental de Golf de Gironde","isPartOf":{"@id":"https:\/\/cdgolf33.com\/#website"},"datePublished":"2018-01-29T20:07:10+00:00","breadcrumb":{"@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdgolf33.com\/index.php\/2018\/01\/29\/interclubs-dhiver-adultes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cdgolf33.com\/"},{"@type":"ListItem","position":2,"name":"INTERCLUBS D&rsquo;HIVER ADULTES"}]},{"@type":"WebSite","@id":"https:\/\/cdgolf33.com\/#website","url":"https:\/\/cdgolf33.com\/","name":"Comit\u00e9 D\u00e9partemental de Golf de Gironde","description":"Le Comit\u00e9 de Gironde de Golf vous souhaite la bienvenue sur son site !","publisher":{"@id":"https:\/\/cdgolf33.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdgolf33.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdgolf33.com\/#organization","name":"Comit\u00e9 de Golf de Gironde","url":"https:\/\/cdgolf33.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/","url":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","contentUrl":"https:\/\/cdgolf33.com\/wp-content\/uploads\/2019\/05\/LOGOCD33.jpg","width":220,"height":233,"caption":"Comit\u00e9 de Golf de Gironde"},"image":{"@id":"https:\/\/cdgolf33.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/comitegolf33"]},{"@type":"Person","@id":"https:\/\/cdgolf33.com\/#\/schema\/person\/0fe3a29db97d77dc619597e8963ba0f5","name":"le Comit\u00e9 de Golf de Gironde","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d0f051f071526df9cb148fdbc91d08090dd58d68fc15de4c9d807e08b07f6c9?s=96&d=mm&r=g","caption":"le Comit\u00e9 de Golf de Gironde"}}]}},"_links":{"self":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts\/3210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/comments?post=3210"}],"version-history":[{"count":0,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/posts\/3210\/revisions"}],"wp:attachment":[{"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/media?parent=3210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/categories?post=3210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdgolf33.com\/index.php\/wp-json\/wp\/v2\/tags?post=3210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}